{"id":16249,"date":"2021-05-08T17:12:10","date_gmt":"2021-05-08T15:12:10","guid":{"rendered":"https:\/\/www.golfclubpetersberg.it\/event\/cristal-cup-2021-8\/"},"modified":"2021-05-08T17:12:26","modified_gmt":"2021-05-08T15:12:26","slug":"cristal-cup-2021-8","status":"publish","type":"tribe_events","link":"https:\/\/golfclubpetersberg.it\/en\/event\/cristal-cup-2021-8\/","title":{"rendered":"CRISTAL CUP 2021"},"content":{"rendered":"<h3>WEEKLEY CUP \u2013 HOTEL CRISTAL GOLF CUP<\/h3>\n<p>Jeden Mittwoch findet das vorgabenwirksame Stableford-Turnier \u201eCRISTAL CUP\u201c statt.<\/p>\n<p>Die Startzeiten sind zwischen 12.00 Uhr und 14.00 Uhr.<br \/>\nBis 12.00 Uhr und ab 14.00 Uhr kann frei gespielt werden.<br \/>\nDie Anmeldung sollte m\u00f6glichst innerhalb Dienstag abend gemacht werden.<br \/>\nAnmeldungen k\u00f6nnen aber auch noch am Mitwoch vormittag gemacht werden, es k\u00f6nnen dann aber nicht mehr alle W\u00fcnsche bez\u00fcglich Startzeit und\/oder<br \/>\nFlightpartner ber\u00fccksichtigt werden.<br \/>\nTurniereinschreibung: \u20ac 15,- f\u00fcr Mitglieder,\u00a0 \u20ac 65,- f\u00fcr G\u00e4ste, inklusive Green-Fee<\/p>\n<p>&nbsp;<\/p>\n<p>Ogni mercoled\u00ec giochiamo la gara stableford infrasettimanale \u201eCRISTAL CUP\u201c.<\/p>\n<p>Le partenze sono tra le ore 12.00 e le ore 14.00.<br \/>\nFino alle ore 12.00 e dopo le ore 14.00 si pu\u00f2 giocare liberamente.<br \/>\nLe iscrizioni dovrebbero essere fatte possibilmente entro marted\u00ec sera.<br \/>\n\u00c8 possibile iscriversi anche mercoled\u00ec mattina, non potranno per\u00f2 essere soddisfatte tutte le preferenze di orari e\/o compagni di gioco.<br \/>\nIscrizione gare: 15,- per i soci, 65,- per ospiti compreso green-fee.<\/p>\n<h3><a href=\"https:\/\/www.hotelcristal.com\/\" target=\"_blank\" rel=\"noopener\">WWW.HOTELCRISTAL.COM<\/a><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>WEEKLEY CUP \u2013 HOTEL CRISTAL GOLF CUP Jeden Mittwoch findet das vorgabenwirksame Stableford-Turnier \u201eCRISTAL CUP\u201c&#8230;<\/p>\n","protected":false},"author":4,"featured_media":11768,"template":"","meta":{"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"tags":[],"tribe_events_cat":[],"class_list":["post-16249","tribe_events","type-tribe_events","status-publish","has-post-thumbnail"],"_links":{"self":[{"href":"https:\/\/golfclubpetersberg.it\/en\/wp-json\/wp\/v2\/tribe_events\/16249","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/golfclubpetersberg.it\/en\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/golfclubpetersberg.it\/en\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/golfclubpetersberg.it\/en\/wp-json\/wp\/v2\/users\/4"}],"version-history":[{"count":0,"href":"https:\/\/golfclubpetersberg.it\/en\/wp-json\/wp\/v2\/tribe_events\/16249\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/golfclubpetersberg.it\/en\/wp-json\/wp\/v2\/media\/11768"}],"wp:attachment":[{"href":"https:\/\/golfclubpetersberg.it\/en\/wp-json\/wp\/v2\/media?parent=16249"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/golfclubpetersberg.it\/en\/wp-json\/wp\/v2\/tags?post=16249"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/golfclubpetersberg.it\/en\/wp-json\/wp\/v2\/tribe_events_cat?post=16249"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}