{"id":21217,"date":"2023-03-13T16:40:58","date_gmt":"2023-03-13T15:40:58","guid":{"rendered":"https:\/\/golfclubpetersberg.it\/event\/business-golf-trophy-curtes\/"},"modified":"2023-06-29T09:57:22","modified_gmt":"2023-06-29T07:57:22","slug":"business-golf-trophy-curtes","status":"publish","type":"tribe_events","link":"https:\/\/golfclubpetersberg.it\/en\/event\/business-golf-trophy-curtes\/","title":{"rendered":"Business Golf Trophy &#8211; Curtes"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-22488 alignnone\" src=\"https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2023\/03\/Business-Golf-Cup-Sieger.jpg\" alt=\"\" width=\"529\" height=\"781\" title=\"\" srcset=\"https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2023\/03\/Business-Golf-Cup-Sieger.jpg 529w, https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2023\/03\/Business-Golf-Cup-Sieger-203x300.jpg 203w\" sizes=\"auto, (max-width: 529px) 100vw, 529px\" \/><\/p>\n<p><a href=\"https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2023\/03\/Business-Golf-Cup-brutto-lordo.pdf\" class=\"mtli_attachment mtli_pdf\">Business-Golf-Cup-brutto-lordo<\/a><br \/>\n<a href=\"https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2023\/03\/Business-Golf-Cup-netto-1.pdf\" class=\"mtli_attachment mtli_pdf\">Business-Golf-Cup-netto-1<\/a><br \/>\n<a href=\"https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2023\/03\/Business-Golf-Cup-netto-2.pdf\" class=\"mtli_attachment mtli_pdf\">Business-Golf-Cup-netto-2<\/a><br \/>\n<a href=\"https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2023\/03\/Business-Golf-Cup-netto-3.pdf\" class=\"mtli_attachment mtli_pdf\">Business-Golf-Cup-netto-3<\/a><\/p>\n<p>&nbsp;<\/p>\n\n\t\t<style>\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 33%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-21217 gallery-columns-3 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2023\/03\/Business-Golf-11-Mittel.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2023\/03\/Business-Golf-11-Mittel-150x150.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2023\/03\/Business-Golf-11-Mittel-150x150.jpeg 150w, https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2023\/03\/Business-Golf-11-Mittel-100x100.jpeg 100w, https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2023\/03\/Business-Golf-11-Mittel-140x140.jpeg 140w, https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2023\/03\/Business-Golf-11-Mittel-500x500.jpeg 500w, https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2023\/03\/Business-Golf-11-Mittel-350x350.jpeg 350w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" title=\"\"><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2023\/03\/Business-Golf-12-Mittel.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2023\/03\/Business-Golf-12-Mittel-150x150.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2023\/03\/Business-Golf-12-Mittel-150x150.jpeg 150w, https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2023\/03\/Business-Golf-12-Mittel-100x100.jpeg 100w, https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2023\/03\/Business-Golf-12-Mittel-140x140.jpeg 140w, https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2023\/03\/Business-Golf-12-Mittel-500x500.jpeg 500w, https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2023\/03\/Business-Golf-12-Mittel-350x350.jpeg 350w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" title=\"\"><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2023\/03\/Business-Golf-13-Mittel.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2023\/03\/Business-Golf-13-Mittel-150x150.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2023\/03\/Business-Golf-13-Mittel-150x150.jpeg 150w, https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2023\/03\/Business-Golf-13-Mittel-100x100.jpeg 100w, https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2023\/03\/Business-Golf-13-Mittel-140x140.jpeg 140w, https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2023\/03\/Business-Golf-13-Mittel-500x500.jpeg 500w, https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2023\/03\/Business-Golf-13-Mittel-350x350.jpeg 350w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" title=\"\"><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2023\/03\/Business-Golf-16-Mittel.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2023\/03\/Business-Golf-16-Mittel-150x150.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2023\/03\/Business-Golf-16-Mittel-150x150.jpeg 150w, https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2023\/03\/Business-Golf-16-Mittel-100x100.jpeg 100w, https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2023\/03\/Business-Golf-16-Mittel-140x140.jpeg 140w, https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2023\/03\/Business-Golf-16-Mittel-500x500.jpeg 500w, https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2023\/03\/Business-Golf-16-Mittel-350x350.jpeg 350w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" title=\"\"><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2023\/03\/Business-Golf-19-Mittel.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2023\/03\/Business-Golf-19-Mittel-150x150.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2023\/03\/Business-Golf-19-Mittel-150x150.jpeg 150w, https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2023\/03\/Business-Golf-19-Mittel-100x100.jpeg 100w, https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2023\/03\/Business-Golf-19-Mittel-140x140.jpeg 140w, https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2023\/03\/Business-Golf-19-Mittel-500x500.jpeg 500w, https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2023\/03\/Business-Golf-19-Mittel-350x350.jpeg 350w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" title=\"\"><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2023\/03\/Business-Golf-22-Mittel.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2023\/03\/Business-Golf-22-Mittel-150x150.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2023\/03\/Business-Golf-22-Mittel-150x150.jpeg 150w, https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2023\/03\/Business-Golf-22-Mittel-100x100.jpeg 100w, https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2023\/03\/Business-Golf-22-Mittel-140x140.jpeg 140w, https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2023\/03\/Business-Golf-22-Mittel-500x500.jpeg 500w, https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2023\/03\/Business-Golf-22-Mittel-350x350.jpeg 350w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" title=\"\"><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2023\/03\/Business-Golf-26-Mittel.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2023\/03\/Business-Golf-26-Mittel-150x150.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2023\/03\/Business-Golf-26-Mittel-150x150.jpeg 150w, https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2023\/03\/Business-Golf-26-Mittel-100x100.jpeg 100w, https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2023\/03\/Business-Golf-26-Mittel-140x140.jpeg 140w, https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2023\/03\/Business-Golf-26-Mittel-500x500.jpeg 500w, https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2023\/03\/Business-Golf-26-Mittel-350x350.jpeg 350w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" title=\"\"><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2023\/03\/Business-Golf-27-Mittel.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2023\/03\/Business-Golf-27-Mittel-150x150.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2023\/03\/Business-Golf-27-Mittel-150x150.jpeg 150w, https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2023\/03\/Business-Golf-27-Mittel-100x100.jpeg 100w, https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2023\/03\/Business-Golf-27-Mittel-140x140.jpeg 140w, https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2023\/03\/Business-Golf-27-Mittel-500x500.jpeg 500w, https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2023\/03\/Business-Golf-27-Mittel-350x350.jpeg 350w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" title=\"\"><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2023\/03\/Business-Golf-34-Mittel.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2023\/03\/Business-Golf-34-Mittel-150x150.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2023\/03\/Business-Golf-34-Mittel-150x150.jpeg 150w, https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2023\/03\/Business-Golf-34-Mittel-100x100.jpeg 100w, https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2023\/03\/Business-Golf-34-Mittel-140x140.jpeg 140w, https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2023\/03\/Business-Golf-34-Mittel-500x500.jpeg 500w, https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2023\/03\/Business-Golf-34-Mittel-350x350.jpeg 350w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" title=\"\"><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-22381 alignnone\" src=\"https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2023\/03\/Bussness-Golf.jpg\" alt=\"\" width=\"604\" height=\"903\" title=\"\" srcset=\"https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2023\/03\/Bussness-Golf.jpg 604w, https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2023\/03\/Bussness-Golf-201x300.jpg 201w\" sizes=\"auto, (max-width: 604px) 100vw, 604px\" \/><\/p>\n<p><a href=\"https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2023\/03\/Buissness-Golf-Cup.pdf\" class=\"mtli_attachment mtli_pdf\">Buissness-Golf-Cup<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Business-Golf-Cup-brutto-lordo Business-Golf-Cup-netto-1 Business-Golf-Cup-netto-2 Business-Golf-Cup-netto-3 &nbsp; &nbsp; Buissness-Golf-Cup &nbsp; &nbsp;<\/p>\n","protected":false},"author":4,"featured_media":22309,"template":"","meta":{"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"tags":[],"tribe_events_cat":[],"class_list":["post-21217","tribe_events","type-tribe_events","status-publish","has-post-thumbnail"],"_links":{"self":[{"href":"https:\/\/golfclubpetersberg.it\/en\/wp-json\/wp\/v2\/tribe_events\/21217","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/golfclubpetersberg.it\/en\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/golfclubpetersberg.it\/en\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/golfclubpetersberg.it\/en\/wp-json\/wp\/v2\/users\/4"}],"version-history":[{"count":0,"href":"https:\/\/golfclubpetersberg.it\/en\/wp-json\/wp\/v2\/tribe_events\/21217\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/golfclubpetersberg.it\/en\/wp-json\/wp\/v2\/media\/22309"}],"wp:attachment":[{"href":"https:\/\/golfclubpetersberg.it\/en\/wp-json\/wp\/v2\/media?parent=21217"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/golfclubpetersberg.it\/en\/wp-json\/wp\/v2\/tags?post=21217"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/golfclubpetersberg.it\/en\/wp-json\/wp\/v2\/tribe_events_cat?post=21217"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}