{"id":5888,"date":"2017-07-31T11:38:30","date_gmt":"2017-07-31T09:38:30","guid":{"rendered":"https:\/\/www.golfclubpetersberg.it\/event\/team-challenge-herren-2016"},"modified":"2017-07-31T11:38:30","modified_gmt":"2017-07-31T09:38:30","slug":"team-challenge-herren-2016","status":"publish","type":"tribe_events","link":"https:\/\/golfclubpetersberg.it\/en\/event\/team-challenge-herren-2016\/","title":{"rendered":"TEAM CHALLENGE HERREN 2016"},"content":{"rendered":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; overlay_strength=&#8221;0.3&#8243;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; width=&#8221;1\/1&#8243; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]TEAM CHALLENGE HERREN 2016<\/p>\n<p>Eingeladene Mannschaften: Alle S\u00fcdtiroler Clubs mit einer Mannschaft von 6 Spielern pro Club<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/golfclubpetersberg.it\/images\/risultati-gare\/Gare-2016\/Team-Challenge-2016.JPG\" alt=\"Team-Challenge-2016\" width=\"950\" height=\"502\" title=\"\"><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/golfclubpetersberg.it\/images\/risultati-gare\/Gare-2016\/Team-Challenge-2016-Teams.JPG\" alt=\"Team-Challenge-2016-Teams\" width=\"950\" height=\"365\" title=\"\"><\/p>\n<p>ERGEBNISSE \u00a0BRUTTO -: RISULTATI: \u00a0 \u00a0\u00a0<a href=\"https:\/\/golfclubpetersberg.it\/images\/risultati-gare\/Gare-2016\/Team-Challenge-2016-lordo.pdf\" class=\"mtli_attachment mtli_pdf\" target=\"_blank\" rel=\"noopener\">LORDO \u00a0<\/a>\u00a0\u00a0 \u00a0<a href=\"https:\/\/golfclubpetersberg.it\/images\/risultati-gare\/Gare-2016\/Team-Challenge-2016-netto.pdf\" class=\"mtli_attachment mtli_pdf\" target=\"_blank\" rel=\"noopener\">NETTO<\/a><\/p>\n<p>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;<\/p>\n<h2>ATTENZIONE &#8211; ACHTUNG ! ! ! ! ! !<\/h2>\n<p>Stra\u00dfensperre von ca. 1 Stunde auf folgenden Abschnitten wegen eines Radrennes.<br \/>\nDie Radfahrer kommen von Cavalese und fahren \u00fcber Aldein &#8211; Petersberg &#8211; Deutschnofen &#8211; Rauth nach Lavaz\u00e9.<br \/>\nDie Stra\u00dfe Eggental-Deutschnofen-Petersberg wird von ca. 8.45 Uhr bis ca. 10.20 gesperrt sein.<br \/>\nDie Stra\u00dfe Montan-Aldein-Petersberg von ca. 8.20 Uhr bis ca. 10.00 Uhr.<\/p>\n<p>Chiusura delle strade a tratti per ca. 1 ora a causa di una gara ciclistica:<br \/>\nI ciclissti arrivano da Cavalese e percorrono la strada Aldino-Monte San Pietro &#8211; Nova Ponente &#8211; Novale &#8211; Lavaz\u00e9.<br \/>\nLa strada Val d&#8217;Ega &#8211; Nova Ponente &#8211; Monte San Pietro sar\u00e0 chiusa ca. dalle ore 8.45 alle ore 10.20.<br \/>\nLa strada Montagna &#8211; Aldino &#8211; Monte San Pietro sar\u00e0 chiusa ca. dalle ore 8.20 alle ore 10.00<\/p>\n<p>Mitteilung des Organisationskommittes Marcialonga Cycling:<\/p>\n<p>Come ogni anno vi informiamo che DOMENICA 12 GIUGNO, passer\u00e0 la 10^ Granfondo di bici<\/p>\n<p>su strada Marcialonga Cycling Craft, con i presunti seguenti orari:<\/p>\n<p>ATTACCO PONTE ALDINO\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 8.37<\/p>\n<p>ALDINO \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 8.53<\/p>\n<p>MONTE SAN PIETRO \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 9.07<\/p>\n<p>NOVA PONENTE \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 9.17<\/p>\n<p>Il passaggio dei ciclisti durer\u00e0 circa un\u2019ora<\/p>\n<p>Vi ringraziamo per informare i vostri clienti sugli orari e sui disagi di chiusura strade.<\/p>\n<p>Cordiali saluti da Predazzo.<\/p>\n<p><a href=\"https:\/\/www.marcialonga.it\" target=\"_blank\" rel=\"noopener\">www.marcialonga.it<\/a><\/p>\n<p>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;-<\/p>\n<p>1. Jede Mannschaft besteht aus maximal 6 Amateurgolfer mit regul\u00e4rem Hcp, welche bei der FIG f\u00fcr den<br \/>\nteilnehmenden Club auch tesseriert sein m\u00fcssen.<\/p>\n<p>2. Die Mannschaft wird durch den Captain vertreten, welcher sowohl Spieler als auch Nichtspieler sein kann.<br \/>\nSpielt der Captain selber, darf wer w\u00e4hrend seiner Runde den restlichen Mannschaftsmitgliedern keine<br \/>\nRatschl\u00e4ge im Sinne der Golfregeln erteilen.<\/p>\n<p>3. Bei den einzelnen Turnieren kann eine Mannschaft auch mehr als 6 Spieler einschreiben, der Captain muss<br \/>\naber vor dem Start des ersten Flights die 6 Spieler namhaft machen, welche f\u00fcr das Mannschaftsergebnis<br \/>\ngewertet werden. Unterl\u00e4sst der Captain diese Meldung z\u00e4hlen die ersten 6 gestarteten Spieler eines jeden<br \/>\nClubs. F\u00fcr das Einzelergebnis Netto und Brutto werden alle Spieler gewertet.<\/p>\n<p>4. Alle Turniere werden als Einzelturniere \u201eMedal\u201c gespielt.<\/p>\n<p>5. Gespielt wird nach den Regeln laut der \u201eR&amp;A Rules Limited\u201c und den Platzregeln des austragenden Clubs.<\/p>\n<p>6. Gespielt werden 3 Turniere, jeweils auf der Golfanlage eines teilnehmenden Clubs. F\u00fcr die Tageswertung<br \/>\nz\u00e4hlen die f\u00fcnf besten NettoErgebnisse<br \/>\nund die vier besten BruttoErgebnisse.<br \/>\nEinzelne Spieler k\u00f6nnen<br \/>\nsowohl in der Nettoals<br \/>\nauch in der BruttoWertung<br \/>\ngewertet werden. Bei Gleichstand z\u00e4hlt das bessere<br \/>\nStreichresultat Brutto, dann das beste Streichresultat Netto (dann 2. Brutto, 2. Netto usw.).<\/p>\n<p>7. F\u00fcr die Endwertung wird jedes Turnier wie folgt gewertet:1. Platz 10 Punkte, 2. Platz 8 Punkte, 3. Platz 6 Punkte,<br \/>\n4. Platz 4 Punkte. Nimmt eine Mannschaft an einem Turnier nicht teil, erh\u00e4lt sie 0 Punkte f\u00fcr die<\/p>\n<p>Gesamtwertung. Bei Gleichstand werden die Punkte der betroffenen Mannschaften zusammengez\u00e4hlt und zu<br \/>\ngleichen Teilen aufgeteilt.<br \/>\nBei Punktegleichstand f\u00fcr die Endwertung, wird nach folgenden Kriterien anhand der<br \/>\nMannschaftstageswertungen entschieden: erstens die meisten Siege, zweitens die meisten zweiten Pl\u00e4tze und<br \/>\ndrittens die meisten dritten Pl\u00e4tze etc.<\/p>\n<p>8. Die Spielerlisten mit Angabe des Captain und\/oder dessen Vertretung m\u00fcssen innerhalb 12.00 Uhr am Vortag<br \/>\ndes jeweiligen Turniers an das Sekretariat des austragenden Clubs geschickt werden. Der austragende Club<br \/>\nsendet die Startzeiten innerhalb 15.00 Uhr des Turniervortages mittels Fax oder Mail an die teilnehmenden<br \/>\nClubs.<\/p>\n<p>9. Abbruch eines Turniers (wetterbedingt \/ durch Sirene)<br \/>\na) sofern alle Teilnehmer bereits mehr als 9 L\u00f6cher gespielt haben, wird maximal 1 Stunde ab dem Moment<br \/>\ndes Sirenensignals gewartet, um das Turnier nach M\u00f6glichkeit fortzusetzen.<br \/>\nb) sollten noch nicht alle Teilnehmer 9 L\u00f6cher absolviert haben, wird maximal 1 Stunde und 30 Minuten<br \/>\ngewartet um das Turnier nach M\u00f6glichkeit fortzusetzen, bis alle Teilnehmer 9 L\u00f6cher absolviert haben.<br \/>\nc) sollte das Turnier noch nicht gestartet und alle Mannschaften anwesend sein, so wird maximal 2 Stunden<br \/>\ngewartet, um das Turnier nach M\u00f6glichkeit \u00fcber 9 Loch zu spielen.<br \/>\nBei Unklarheiten entscheidet der Clubsekret\u00e4r des gastgebenden Clubs gemeinsam mit den Captains wobei der<br \/>\nSekret\u00e4r und die anwesenden Captains jeweils eine Stimme haben und mit Mehrheit entscheiden.<\/p>\n<p>10. Die Einschreibegeb\u00fchr betr\u00e4gt \u20ac 20,pro<br \/>\nPerson inklusive eines gemeinsamen Essens (zwei Gerichte, Wein<br \/>\nund Wasser). Das Greenfee wird auf 35,00 Euro festgelegt.<\/p>\n<p>11. Bei jedem Turnier werden der erste Brutto und der Erste Netto pr\u00e4miert. Bei Gleichstand gelten die Regeln des<br \/>\nGolfverbandes. Der Wanderpokal bzw. die Ehrentafel bleibt in dem Club, welcher im Vorjahr die<br \/>\nGesamtwertung gewonnen hat. Alle Turniere sind vorgabewirksam zu spielen.<\/p>\n<p>12. Der austragende Club organisiert jeweils die Verpflegung und organisiert die Startzeiten am Samstag, 30.04 im<br \/>\nGC Passeier ab 12.00 Uhr, am Sonntag, 12.06. im GC Petersberg ab 9.00 Uhr und am Samstag 27.08. im GC<br \/>\nEppan ab 12.00 Uhr.<\/p>\n<p>13. Sollte eine Etappe aus welchen Gr\u00fcnden auch immer vor dem Start abgesagt<\/p>\n<p>eine Etappe aus welchen Gr\u00fcnden auch immer vor dem Start abgesagt werden, wird der Ersatztermin<br \/>\nvon den Kapit\u00e4nen und dem betroffenen Club koordiniert.[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; overlay_strength=&#8221;0.3&#8243;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; width=&#8221;1\/1&#8243; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;1882,1883,1884,1885,1886,1887,1888,1889&#8243; layout=&#8221;4&#8243; masonry_style=&#8221;true&#8221; gallery_style=&#8221;3&#8243; load_in_animation=&#8221;fade_in_from_bottom&#8221; img_size=&#8221;medium&#8221;][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; overlay_strength=&#8221;0.3&#8243;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; width=&#8221;1\/1&#8243; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"template":"","meta":{"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"tags":[],"tribe_events_cat":[],"class_list":["post-5888","tribe_events","type-tribe_events","status-publish"],"_links":{"self":[{"href":"https:\/\/golfclubpetersberg.it\/en\/wp-json\/wp\/v2\/tribe_events\/5888","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/golfclubpetersberg.it\/en\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/golfclubpetersberg.it\/en\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/golfclubpetersberg.it\/en\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/golfclubpetersberg.it\/en\/wp-json\/wp\/v2\/tribe_events\/5888\/revisions"}],"wp:attachment":[{"href":"https:\/\/golfclubpetersberg.it\/en\/wp-json\/wp\/v2\/media?parent=5888"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/golfclubpetersberg.it\/en\/wp-json\/wp\/v2\/tags?post=5888"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/golfclubpetersberg.it\/en\/wp-json\/wp\/v2\/tribe_events_cat?post=5888"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}