{"id":25371,"date":"2024-12-09T15:25:08","date_gmt":"2024-12-09T14:25:08","guid":{"rendered":"https:\/\/golfclubpetersberg.it\/safeguarding\/"},"modified":"2025-02-19T16:01:18","modified_gmt":"2025-02-19T15:01:18","slug":"safeguarding","status":"publish","type":"page","link":"https:\/\/golfclubpetersberg.it\/it\/safeguarding\/","title":{"rendered":"Safeguarding"},"content":{"rendered":"[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#ffffff&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;7%&#8221; bottom_padding=&#8221;7%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; offset=&#8221;vc_hidden-sm vc_hidden-xs&#8221;][\/vc_column][vc_column column_padding=&#8221;padding-2-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;SAFEGUARDING ASV Golf Club Petersberg&#8221; font_container=&#8221;tag:h1|text_align:center|color:%236e8956&#8243; google_fonts=&#8221;font_family:Roboto%20Condensed%3A300%2C300italic%2Cregular%2Citalic%2C700%2C700italic|font_style:700%20bold%20regular%3A700%3Anormal&#8221; css=&#8221;&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;100&#8243;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]La ASD Golf Club Petersberg si impegna a garantire un ambiente sicuro e rispettoso per tutti e non sono tollerati violenze, molestie e discriminazioni di qualsiasi tipo. Invitiamo tutte le persone presenti nella nostra struttura (in particolare i soci, ospiti e collaboratori) a dare il loro contributo per garantire un ambiente sicuro e rispettoso.<\/p>\n<p><strong><u>COSA SONO LE MOLESTIE ?<\/u><\/strong><\/p>\n<p>Le molestie includono qualsiasi comportamento indesiderato e inappropriato che possa creare un ambiente ostile, intimidatorio o offensivo.<\/p>\n<p>Questo pu\u00f2 comprendere, ma non \u00e8 limitato a:<\/p>\n<ul>\n<li>Commenti offensivi<\/li>\n<li>Gesti inappropriati<\/li>\n<li>Contatti fisici non consensuali<\/li>\n<li>Atti di bullismo o intimidazione<\/li>\n<li>Avances sessuali indesiderate<\/li>\n<\/ul>\n<p><strong><u>IL NOSTRO IMPEGNO:<\/u><\/strong><\/p>\n<ul>\n<li>Rispetto \u2013 qualsiasi persona deve rispettare la dignit\u00e0 e i diritti degli altri.<\/li>\n<li>Sicurezza \u2013 vogliamo garantire un ambiente sicuro per tutti, libero da molestie e discriminazioni.<\/li>\n<li>Supporto &#8211; offriamo supporto a chiunque sia vittima o testimone di molestie.<\/li>\n<\/ul>\n<p><strong><u>COSA FARE SE SEI VITTIMA O TESTIMONE DI MOLESTIE:<\/u><\/strong><\/p>\n<ul>\n<li>Non rimanere in silenzio: parla con una persona di fiducia.<\/li>\n<li>Segnala l&#8217;episodio: rivolgiti al Responsabile contro gli abusi, le violenze e le discriminazioni.<\/li>\n<li>Documenta: prendi nota di tutti i dettagli pertinenti (date, luoghi, persone coinvolte).<\/li>\n<li>Richiedi supporto: il nostro Responsabile contro gli abusi, le violenze e le discriminazioni \u00e8 disponibile per qualsiasi supporto inclusa l\u2019assistenza morale e l\u2019orientamento verso servizi esterni, se necessario.<\/li>\n<\/ul>\n<p><strong><u>CONTATTI UTILI E STRUMENTI DI SEGNALAZIONE<\/u><\/strong><\/p>\n<p>Safeguarding officer Federazione Italiana Golf:\u00a0<a href=\"mailto:safeguarding.officer@federgolf.it\">safeguarding.officer@federgolf.it<\/a><\/p>\n<p>Responsabile contro abusi, violenze e discriminazioni della<br \/>\nAssociazione Sportiva Dilettantistica Golf Club Petersberg \u00e8:<\/p>\n<p>Hans-Peter Thaler\u00a0 &#8211;\u00a0 \u00a0Mail:\u00a0\u00a0<a href=\"mailto:safeguarding.gc.petersberg@gmail.com\">safeguarding.gc.petersberg@gmail.com<\/a><br \/>\nTel: 0471.615122<\/p>\n<p><a href=\"https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2024\/12\/2024-Safeguarding-Codice-Condotta-GCP.pdf\" class=\"mtli_attachment mtli_pdf\">2024-Safeguarding-Codice-Condotta-GCP<\/a><\/p>\n<p><a href=\"https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2024\/12\/2024-Safeguarding-Modello-organizzativo-GCP.pdf\" class=\"mtli_attachment mtli_pdf\">2024-Safeguarding-Modello-organizzativo-GCP<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; offset=&#8221;vc_hidden-sm vc_hidden-xs&#8221;][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#ffffff&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;7%&#8221; bottom_padding=&#8221;7%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-25371","page","type-page","status-publish"],"_links":{"self":[{"href":"https:\/\/golfclubpetersberg.it\/it\/wp-json\/wp\/v2\/pages\/25371","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/golfclubpetersberg.it\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/golfclubpetersberg.it\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/golfclubpetersberg.it\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/golfclubpetersberg.it\/it\/wp-json\/wp\/v2\/comments?post=25371"}],"version-history":[{"count":0,"href":"https:\/\/golfclubpetersberg.it\/it\/wp-json\/wp\/v2\/pages\/25371\/revisions"}],"wp:attachment":[{"href":"https:\/\/golfclubpetersberg.it\/it\/wp-json\/wp\/v2\/media?parent=25371"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}