{"id":3300,"date":"2017-07-05T12:00:04","date_gmt":"2017-07-05T10:00:04","guid":{"rendered":"https:\/\/www.golfclubpetersberg.it\/sitemap"},"modified":"2017-07-05T12:00:04","modified_gmt":"2017-07-05T10:00:04","slug":"sitemap","status":"publish","type":"page","link":"https:\/\/golfclubpetersberg.it\/it\/sitemap\/","title":{"rendered":"Sitemap"},"content":{"rendered":"[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; bg_color=&#8221;#ffffff&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; top_padding=&#8221;7%&#8221; bottom_padding=&#8221;7%&#8221; overlay_strength=&#8221;0.3&#8243;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; width=&#8221;1\/6&#8243; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; offset=&#8221;vc_hidden-sm vc_hidden-xs&#8221;][\/vc_column][vc_column column_padding=&#8221;padding-2-percent&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; width=&#8221;2\/3&#8243; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;Sitemap&#8221; font_container=&#8221;tag:h1|text_align:center|color:%236e8956&#8243; google_fonts=&#8221;font_family:Roboto%20Condensed%3A300%2C300italic%2Cregular%2Citalic%2C700%2C700italic|font_style:700%20bold%20regular%3A700%3Anormal&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;100&#8243;][vc_column_text]<div class=\"wsp-container\"><h2 class=\"wsp-pages-title\">Pagine<\/h2>\n<ul class=\"wsp-pages-list\">\n<li class=\"page_item page-item-3050\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/1-2\/\">1<\/a><\/li>\n<li class=\"page_item page-item-3055\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/10-2\/\">10<\/a><\/li>\n<li class=\"page_item page-item-3059\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/11-2\/\">11<\/a><\/li>\n<li class=\"page_item page-item-3064\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/12-2\/\">12<\/a><\/li>\n<li class=\"page_item page-item-3068\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/13-2\/\">13<\/a><\/li>\n<li class=\"page_item page-item-3074\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/14-2\/\">14<\/a><\/li>\n<li class=\"page_item page-item-3078\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/15-2\/\">15<\/a><\/li>\n<li class=\"page_item page-item-3082\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/16-2\/\">16<\/a><\/li>\n<li class=\"page_item page-item-3087\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/17-2\/\">17<\/a><\/li>\n<li class=\"page_item page-item-3091\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/18-2\/\">18<\/a><\/li>\n<li class=\"page_item page-item-3137\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/18-buche\/\">18 buche<\/a><\/li>\n<li class=\"page_item page-item-3099\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/2-2\/\">2<\/a><\/li>\n<li class=\"page_item page-item-3104\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/3-2\/\">3<\/a><\/li>\n<li class=\"page_item page-item-3108\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/4-2\/\">4<\/a><\/li>\n<li class=\"page_item page-item-3112\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/5-2\/\">5<\/a><\/li>\n<li class=\"page_item page-item-3117\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/6-2\/\">6<\/a><\/li>\n<li class=\"page_item page-item-3124\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/7-2\/\">7<\/a><\/li>\n<li class=\"page_item page-item-3119\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/8-2\/\">8<\/a><\/li>\n<li class=\"page_item page-item-3121\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/9-2\/\">9<\/a><\/li>\n<li class=\"page_item page-item-14521\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/campionati_sociali\/\">Campionati sociali<\/a><\/li>\n<li class=\"page_item page-item-3311\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/campo-pratica\/\">Campo pratica<\/a><\/li>\n<li class=\"page_item page-item-8254\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/comunicazioni-ai-soci\/\">Comunicazioni ai soci<\/a><\/li>\n<li class=\"page_item page-item-3435\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/contatti\/\">Contatti<\/a><\/li>\n<li class=\"page_item page-item-3229\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/convenzioni\/\">Convenzioni<\/a><\/li>\n<li class=\"page_item page-item-3234\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/corsi\/\">Corsi<\/a><\/li>\n<li class=\"page_item page-item-6164\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/corsi-per-bambini\/\">Corsi per bambini<\/a><\/li>\n<li class=\"page_item page-item-3166\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/lassociazione\/\">Diventare Socio<\/a><\/li>\n<li class=\"page_item page-item-3433\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/download\/\">Download<\/a><\/li>\n<li class=\"page_item page-item-3304\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/events\/\">Eventi e tornei<\/a><\/li>\n<li class=\"page_item page-item-3258\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/facebook\/\">Facebook<\/a><\/li>\n<li class=\"page_item page-item-3437\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/gallery\/\">Gallery<\/a><\/li>\n<li class=\"page_item page-item-3209\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/golf-alto-adige\/\">Golf Alto Adige<\/a><\/li>\n<li class=\"page_item page-item-3416\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/\">Golfclub Petersberg<\/a><\/li>\n<li class=\"page_item page-item-3218\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/handicap\/\">Handicap \/ Federazione Italiana Golf<\/a><\/li>\n<li class=\"page_item page-item-3266\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/hotel-associati\/\">Hotel associati<\/a><\/li>\n<li class=\"page_item page-item-3317\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/i-dintorni\/\">I dintorni<\/a><\/li>\n<li class=\"page_item page-item-3171\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/i-nostri-servizi\/\">I nostri servizi<\/a><\/li>\n<li class=\"page_item page-item-3272\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/i-presidenti\/\">I presidenti<\/a><\/li>\n<li class=\"page_item page-item-3222\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/impressum\/\">Impressum<\/a><\/li>\n<li class=\"page_item page-item-3224\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/info-federazione-golf\/\">Info \u2013 Federazione Golf<\/a><\/li>\n<li class=\"page_item page-item-3177\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/storia\/\">La nostra storia<\/a><\/li>\n<li class=\"page_item page-item-6186\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/ladies-days\/\">Ladies Days<\/a><\/li>\n<li class=\"page_item page-item-3248\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/links\/\">Links<\/a><\/li>\n<li class=\"page_item page-item-6141\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/match-play\/\">Match Play<\/a><\/li>\n<li class=\"page_item page-item-3253\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/membership\/\">Membership<\/a><\/li>\n<li class=\"page_item page-item-3260\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/organigramma\/\">Organigramma<\/a><\/li>\n<li class=\"page_item page-item-3143\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/pacchetti-principianti\/\">Pacchetti principianti<\/a><\/li>\n<li class=\"page_item page-item-3280\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/prezzi\/\">Prezzi<\/a><\/li>\n<li class=\"page_item page-item-3149\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/prima_esperienza_gratuita\/\">PRIMA ESPERIENZA GRATUITA<\/a><\/li>\n<li class=\"page_item page-item-3278\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/privacy\/\">Privacy<\/a><\/li>\n<li class=\"page_item page-item-21460\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/ben-mannix\/\">Pro &#8211; Ben Mannix<\/a><\/li>\n<li class=\"page_item page-item-7149\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/pro-shop\/\">Pro Shop<\/a><\/li>\n<li class=\"page_item page-item-3284\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/rating\/\">Rating<\/a><\/li>\n<li class=\"page_item page-item-3291\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/regole-regole-locali\/\">Regole del golf e regole locali<\/a><\/li>\n<li class=\"page_item page-item-20503\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/regole-del-golf-e-regole-locali\/\">Regole del golf e regole locali<\/a><\/li>\n<li class=\"page_item page-item-3296\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/ristorante\/\">Ristorante<\/a><\/li>\n<li class=\"page_item page-item-25371\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/safeguarding\/\">Safeguarding<\/a><\/li>\n<li class=\"page_item page-item-3302\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/score\/\">Score<\/a><\/li>\n<li class=\"page_item page-item-6148\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/score-doro\/\">SCORE D\u2019ORO<\/a><\/li>\n<li class=\"page_item page-item-3214\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/scuola-di-golf\/\">Scuola di Golf<\/a><\/li>\n<li class=\"page_item page-item-6172\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/senior-days\/\">Senior Days<\/a><\/li>\n<li class=\"page_item page-item-3300\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/sitemap\/\">Sitemap<\/a><\/li>\n<li class=\"page_item page-item-14490\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/social-championsship\/\">Social Championsship<\/a><\/li>\n<li class=\"page_item page-item-6051\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/star-tour\/\">Star Tour<\/a><\/li>\n<li class=\"page_item page-item-3319\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/video-sektion\/\">Video Sektion<\/a><\/li>\n<li class=\"page_item page-item-3338\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/webcam\/\">Webcam<\/a><\/li>\n<li class=\"page_item page-item-6156\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/weekly-cup\/\">Weekly Cup<\/a><\/li>\n<li class=\"page_item page-item-14710\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/news\/\">Storie e curiosit\u00e0<\/a><\/li>\n<\/ul>\n<h2 class=\"wsp-posts-title\">Articoli suddivisi per categoria<\/h2>\n<ul class=\"wsp-posts-list\">\n\t<li><strong class=\"wsp-category-title\">Category: <a href=\"https:\/\/golfclubpetersberg.it\/it\/hotel-partner\/\">Hotel partner<\/a><\/strong>\n<ul class=\"wsp-posts-list\">\t\t<li class=\"wsp-post\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/alma-alpina-lodge\/\">Alma Alpina Lodge **** &#8211; Adults Only<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/hotel-regglbergerhof-s\/\">Hotel Regglbergerhof ***S<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/manna-resort\/\">Manna Resort *****<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/hotel-peter\/\">Hotel Peter ****<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/gasthof-weber\/\">Gasthof Weber<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/gasthof-albergo-wieser\/\">Wieser *** &#8211; Guesthouse<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/hotel-gasthof-krone\/\">Hotel Gasthof Krone ***<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/aparthotel-my-daum\/\">Aparthotel My Daum<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/panoramahotel-obkircher\/\">Panoramahotel Obkircher ***<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/garni-sonnegg\/\">Garni Sonnegg **<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/hotel-erica-s\/\">Hotel Erica ****S<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/hotel-pfoesl\/\">Hotel Pf\u00f6sl ****s<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/ganis-resort\/\">Ganis Resort ****S<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/sporthotel-obereggen-s\/\">SPORTHOTEL OBEREGGEN ****s<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/golfclubpetersberg.it\/en\/hotel-tenz\/\">Hotel Tenz ****<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/hotel-tenz\/\">Hotel Tenz ****<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/hotel-cristal-s\/\">Hotel Cristal ****S<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/hotel-sonnalp-s\/\">Hotel Sonnalp ****S<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/schwarz-adler-turmhotel\/\">Schwarz Adler Turmhotel ***<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/hotel_rotwand-s\/\">Hotel Rotwand ***s<\/a><\/li>\n<\/ul><\/li>\n\t<li><strong class=\"wsp-category-title\">Category: <a href=\"https:\/\/golfclubpetersberg.it\/it\/i-dintorni\/\">I dintorni<\/a><\/strong>\n<ul class=\"wsp-posts-list\">\t\t<li class=\"wsp-post\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/il-santuario-di-pietralba\/\">Il Santuario di Pietralba<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/val-di-fiemme\/\">Val di Fiemme<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/lago-di-caldaro\/\">Lago di Caldaro<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/raccolta-funghi-alto-adige\/\">Raccolta funghi &#8211; Alto Adige<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/valdega-obereggen-nova-ponente\/\">VAL D&#8217;EGA &#8211; OBEREGGEN<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/parco-geologico-bletterbach\/\">Parco geologico Bletterbach<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/passeggiate-nordic-walking-alto-adige\/\">Passeggiate e Nordic Walking in Alto Adige<\/a><\/li>\n<\/ul><\/li>\n\t<li><strong class=\"wsp-category-title\">Category: <a href=\"https:\/\/golfclubpetersberg.it\/it\/news\/\">News<\/a><\/strong>\n<ul class=\"wsp-posts-list\">\t\t<li class=\"wsp-post\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/pacchetti-principianti\/\">Pacchetti per principianti<\/a><\/li>\n\t\t<li class=\"wsp-post\"><a href=\"https:\/\/golfclubpetersberg.it\/it\/corso-di-introduzione_ben\/\">ORA GRATUITA DI INTRODUZIONE NEL GOLF CON BEN MANNIX,  OGNI SABATO 12:00 &#8211; 13:00<\/a><\/li>\n<\/ul><\/li>\n<\/ul>\n<h2 class=\"wsp-wpdmpros-title\">Download<\/h2>\n<ul class=\"wsp-wpdmpros-list\">\n<li><a href=\"https:\/\/golfclubpetersberg.it\/it\/download\/regole-locali-2024\/\">Regole Locali 2024<\/a><\/li>\n<li><a href=\"https:\/\/golfclubpetersberg.it\/it\/download\/platzregeln-2024\/\">Platzregeln 2024<\/a><\/li>\n<li><a href=\"https:\/\/golfclubpetersberg.it\/it\/download\/logo-golf-club-petersberg-pdf\/\">Logo Golf Club Petersberg - PDF<\/a><\/li>\n<li><a href=\"https:\/\/golfclubpetersberg.it\/it\/download\/logo-golf-club-petersberg-jpg\/\">Logo Golf Club Petersberg - JPG<\/a><\/li>\n<li><a href=\"https:\/\/golfclubpetersberg.it\/it\/download\/domanda-di-ammissione-al-club-2\/\">Domanda di ammissione al Club<\/a><\/li>\n<li><a href=\"https:\/\/golfclubpetersberg.it\/it\/download\/top-10-radius\/\">Top 10 Radius<\/a><\/li>\n<li><a href=\"https:\/\/golfclubpetersberg.it\/it\/download\/golf-guide-tipp-2\/\">Golf Guide Tipp<\/a><\/li>\n<li><a href=\"https:\/\/golfclubpetersberg.it\/it\/download\/mondo-del-golf\/\">Il mondo del Golf<\/a><\/li>\n<li><a href=\"https:\/\/golfclubpetersberg.it\/it\/download\/weitblick\/\">WeitBlick<\/a><\/li>\n<li><a href=\"https:\/\/golfclubpetersberg.it\/it\/download\/vogue-japan\/\">Vogue Japan<\/a><\/li>\n<li><a href=\"https:\/\/golfclubpetersberg.it\/it\/download\/antrag-um-aufnahme-als-ordentliches-mitglied-im-golf-club-petersberg\/\">ANTRAG UM AUFNAHME ALS ORDENTLICHES MITGLIED IM  GOLF CLUB PETERSBERG<\/a><\/li>\n<li><a href=\"https:\/\/golfclubpetersberg.it\/it\/download\/statuto-asv-golf-club-petersberg\/\">Statuto ASV Golf CLub Petersberg<\/a><\/li>\n<li><a href=\"https:\/\/golfclubpetersberg.it\/it\/download\/statut-asv-golf-club-petersberg\/\">Statut ASV Golf CLub Petersberg<\/a><\/li>\n<\/ul>\n<h2 class=\"wsp-tribe_eventss-title\">Eventi<\/h2>\n<ul class=\"wsp-tribe_eventss-list\">\n<li><a href=\"https:\/\/golfclubpetersberg.it\/it\/event\/vice-presidents-golf-trophy\/\">VICE-PRESIDENT'S GOLF TROPHY<\/a><\/li>\n<li><a href=\"https:\/\/golfclubpetersberg.it\/it\/event\/fineco-golf-club-2026-invitational\/\">FINECO Golf Club 2026 - Invitational<\/a><\/li>\n<li><a href=\"https:\/\/golfclubpetersberg.it\/it\/event\/business-golf-trophy-2\/\">Business Golf Trophy<\/a><\/li>\n<li><a href=\"https:\/\/golfclubpetersberg.it\/it\/event\/cristal-cup-2026\/\">Cristal Cup 2026<\/a><\/li>\n<li><a href=\"https:\/\/golfclubpetersberg.it\/it\/event\/finale-vss-raiffeisen-golf-trophy-2\/\">Finale \u2013 VSS \/ RAIFFEISEN GOLF TROPHY<\/a><\/li>\n<li><a href=\"https:\/\/golfclubpetersberg.it\/it\/event\/presidents-cup-2026\/\">PRESIDENT'S CUP 2026<\/a><\/li>\n<li><a href=\"https:\/\/golfclubpetersberg.it\/it\/event\/cadore-asfalti-golf-cup\/\">Cadore Asfalti - Unifarco Golf Trophy<\/a><\/li>\n<li><a href=\"https:\/\/golfclubpetersberg.it\/it\/event\/31-trofeo-gioielleria-fasoli-2\/\">31\u00b0 TROFEO GIOIELLERIA FASOLI<\/a><\/li>\n<li><a href=\"https:\/\/golfclubpetersberg.it\/it\/event\/31-trofeo-gioielleria-fasoli\/\">31\u00b0 TROFEO GIOIELLERIA FASOLI<\/a><\/li>\n<li><a href=\"https:\/\/golfclubpetersberg.it\/it\/event\/aci-golf-2026\/\">ACI GOLF 2026<\/a><\/li>\n<li><a href=\"https:\/\/golfclubpetersberg.it\/it\/event\/forst-sporthilfe-golf-charity-2\/\">Forst Sporthilfe Golf Charity<\/a><\/li>\n<li><a href=\"https:\/\/golfclubpetersberg.it\/it\/event\/promis-golf-cup-2\/\">Promis Golf Cup<\/a><\/li>\n<li><a href=\"https:\/\/golfclubpetersberg.it\/it\/event\/cristal-cup-2026-28\/\">Cristal Cup 2026<\/a><\/li>\n<li><a href=\"https:\/\/golfclubpetersberg.it\/it\/event\/cristal-cup-2026-27\/\">Cristal Cup 2026<\/a><\/li>\n<li><a href=\"https:\/\/golfclubpetersberg.it\/it\/event\/cristal-cup-2026-26\/\">Cristal Cup 2026<\/a><\/li>\n<li><a href=\"https:\/\/golfclubpetersberg.it\/it\/event\/cristal-cup-2026-25\/\">Cristal Cup 2026<\/a><\/li>\n<li><a href=\"https:\/\/golfclubpetersberg.it\/it\/event\/cristal-cup-2026-24\/\">Cristal Cup 2026<\/a><\/li>\n<li><a href=\"https:\/\/golfclubpetersberg.it\/it\/event\/cristal-cup-2026-23\/\">Cristal Cup 2026<\/a><\/li>\n<li><a href=\"https:\/\/golfclubpetersberg.it\/it\/event\/cristal-cup-2026-22\/\">Cristal Cup 2026<\/a><\/li>\n<li><a href=\"https:\/\/golfclubpetersberg.it\/it\/event\/cristal-cup-2026-21\/\">Cristal Cup 2026<\/a><\/li>\n<li><a href=\"https:\/\/golfclubpetersberg.it\/it\/event\/cristal-cup-2026-20\/\">Cristal Cup 2026<\/a><\/li>\n<li><a href=\"https:\/\/golfclubpetersberg.it\/it\/event\/cristal-cup-2026-19\/\">Cristal Cup 2026<\/a><\/li>\n<li><a href=\"https:\/\/golfclubpetersberg.it\/it\/event\/cristal-cup-2026-18\/\">Cristal Cup 2026<\/a><\/li>\n<li><a href=\"https:\/\/golfclubpetersberg.it\/it\/event\/cristal-cup-2026-17\/\">Cristal Cup 2026<\/a><\/li>\n<li><a href=\"https:\/\/golfclubpetersberg.it\/it\/event\/cristal-cup-2026-15\/\">Cristal Cup 2026<\/a><\/li>\n<li><a href=\"https:\/\/golfclubpetersberg.it\/it\/event\/cristal-cup-2026-14\/\">Cristal Cup 2026<\/a><\/li>\n<li><a href=\"https:\/\/golfclubpetersberg.it\/it\/event\/cristal-cup-2026-13\/\">Cristal Cup 2026<\/a><\/li>\n<\/ul>\n<h2 class=\"wsp-wpdmcategorys-title\">Categorie<\/h2>\n<ul class=\"wsp-wpdmcategorys-list\">\n<li><a href=\"https:\/\/golfclubpetersberg.it\/it\/download-category\/docs\/\">Docs<\/a><\/li>\n<li><a href=\"https:\/\/golfclubpetersberg.it\/it\/download-category\/logos\/\">Offizielle Logos - Loghi ufficiali<\/a><\/li>\n<li><a href=\"https:\/\/golfclubpetersberg.it\/it\/download-category\/press-area\/\">Press Area<\/a><\/li>\n<\/ul>\n<\/div>[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; width=&#8221;1\/6&#8243; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; offset=&#8221;vc_hidden-sm vc_hidden-xs&#8221;][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; bg_color=&#8221;#ffffff&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; top_padding=&#8221;7%&#8221; bottom_padding=&#8221;7%&#8221; overlay_strength=&#8221;0.3&#8243;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"class_list":["post-3300","page","type-page","status-publish"],"_links":{"self":[{"href":"https:\/\/golfclubpetersberg.it\/it\/wp-json\/wp\/v2\/pages\/3300","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/golfclubpetersberg.it\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/golfclubpetersberg.it\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/golfclubpetersberg.it\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/golfclubpetersberg.it\/it\/wp-json\/wp\/v2\/comments?post=3300"}],"version-history":[{"count":0,"href":"https:\/\/golfclubpetersberg.it\/it\/wp-json\/wp\/v2\/pages\/3300\/revisions"}],"wp:attachment":[{"href":"https:\/\/golfclubpetersberg.it\/it\/wp-json\/wp\/v2\/media?parent=3300"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}