{"id":2950,"date":"2017-07-12T17:20:11","date_gmt":"2017-07-12T15:20:11","guid":{"rendered":"https:\/\/www.golfclubpetersberg.it\/ganischgerhof-s"},"modified":"2017-08-18T18:42:38","modified_gmt":"2017-08-18T16:42:38","slug":"ganischgerhof-s","status":"publish","type":"post","link":"https:\/\/golfclubpetersberg.it\/it\/ganischgerhof-s\/","title":{"rendered":"Ganischgerhof ****S"},"content":{"rendered":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; overlay_strength=&#8221;0.3&#8243;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; width=&#8221;1\/6&#8243; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]\n<div class=\"pos-description\"><\/div>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; width=&#8221;2\/3&#8243; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]\n<div class=\"pos-description\">\n<div class=\"element element-textarea \">\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-6664 size-medium\" src=\"https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2017\/07\/03_GolfhotelDolomiten-S\u00fcdtirol_Ganischgerhof-300x148.jpg\" alt=\"\" width=\"300\" height=\"148\" title=\"\" srcset=\"https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2017\/07\/03_GolfhotelDolomiten-S\u00fcdtirol_Ganischgerhof-300x148.jpg 300w, https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2017\/07\/03_GolfhotelDolomiten-S\u00fcdtirol_Ganischgerhof-768x379.jpg 768w, https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2017\/07\/03_GolfhotelDolomiten-S\u00fcdtirol_Ganischgerhof-1024x505.jpg 1024w, https:\/\/golfclubpetersberg.it\/wp-content\/uploads\/2017\/07\/03_GolfhotelDolomiten-S\u00fcdtirol_Ganischgerhof.jpg 1500w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<div class=\"pos-description\"><\/div>\n<div class=\"pos-bottom\">Ganischgerhof<br \/>\nL\u2019Hotel Ganischgerhof Mountain Resort &amp; SPA gode, tra gli amici del golf, di<br \/>\nun\u2019ottima reputazione. Questo grazie non solamente all\u2019atmosfera che si respira<br \/>\nnella casa ed alla sua eccellente cucina, ma anche per il suo servizio golf a 360\u00b0.<br \/>\nChi alloggia presso l\u2019hotel, pu\u00f2 anche prendere parte ai tour di golf settimanali<br \/>\nverso i campi da golf pi\u00f9 belli dell\u2019Alto Adige.<br \/>\nLe offerte Relax e Gourmet del nostro hotel golf in Alto Adige sono, tra tutte le proposte,<br \/>\nquelle pi\u00f9 gettonate. Immaginate: un panorama mozzafiato, ampi giardini e benessere<br \/>\ngrazie alla nostra Oasi SPA completa di piscina, saune, bagni turchi e tutto ci\u00f2 che il corpo e<br \/>\nla mente bramano per lasciarsi andare e fare il pieno di energia.<br \/>\n\u201eAs you like it\u201c \u00e8 il motto della \u201ePensione \u00be Ganischger Plus+\u201c. Provate questa esperienza<br \/>\nnon solamente al Ganischgerhof, ma anche in tutte le altre nostre strutture. Il nostro<br \/>\nconcetto gourmet, unico nel suo genere, vi sapr\u00e0 viziare esattamente quando lo desiderate<br \/>\nvoi, con piatti regionali e mediterranei, dolci e squisiti snack. Naturalmente tutti i giorni<br \/>\nserviamo la colazione anche per i pi\u00f9 dormiglioni fino alle ore 11.<br \/>\nIn qualit\u00e0 di ospite del Ganischgerhof avete diritto alla Golf-In-Card S\u00fcdtirol. Grazie a<br \/>\nquesta carta potrete usufruire di condizioni allettanti e del 20% di sconto sul Green Fee di<br \/>\ntutti i campi altoatesini che aderiscono all\u2019iniziativa. In soli 10 minuti vi accompagneremo<br \/>\ncomodamente e gratuitamente al Golf Club Petersberg.<\/div>\n<div><\/div>\n<div class=\"pos-bottom\">Famiglia Pichler<br \/>\nVia Rio Nero 22<br \/>\nI-39050 Nova Ponente<\/div>\n<div><\/div>\n<div class=\"pos-bottom\">Contatti<br \/>\n+39 0471 616 504<\/div>\n<div class=\"pos-bottom\">office@ganischgerhof.com<\/div>\n<div class=\"pos-bottom\"><a href=\"https:\/\/www.ganischger.com\" target=\"_blank\" rel=\"noopener\">https:\/\/www.ganischger.com<\/a><\/div>\n<div class=\"pos-bottom\"><\/div>\n<\/div>\n<\/div>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; width=&#8221;1\/6&#8243; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; overlay_strength=&#8221;0.3&#8243;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; width=&#8221;1\/1&#8243; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;6463,6460,6457,6454,6451,6448,6445,6424,6427,6430,6433,6436,6439,6442,6421,6418,6415,6412,6409,6406,6403,6388,6391,6394,6397,6400&#8243; layout=&#8221;4&#8243; masonry_style=&#8221;true&#8221; gallery_style=&#8221;7&#8243; load_in_animation=&#8221;fade_in_from_bottom&#8221;][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; overlay_strength=&#8221;0.3&#8243;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; width=&#8221;1\/6&#8243; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":6664,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[36],"tags":[],"class_list":["post-2950","post","type-post","status-publish","format-standard","has-post-thumbnail","category-hotel-partner"],"_links":{"self":[{"href":"https:\/\/golfclubpetersberg.it\/it\/wp-json\/wp\/v2\/posts\/2950","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/golfclubpetersberg.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/golfclubpetersberg.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/golfclubpetersberg.it\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/golfclubpetersberg.it\/it\/wp-json\/wp\/v2\/comments?post=2950"}],"version-history":[{"count":0,"href":"https:\/\/golfclubpetersberg.it\/it\/wp-json\/wp\/v2\/posts\/2950\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/golfclubpetersberg.it\/it\/wp-json\/wp\/v2\/media\/6664"}],"wp:attachment":[{"href":"https:\/\/golfclubpetersberg.it\/it\/wp-json\/wp\/v2\/media?parent=2950"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/golfclubpetersberg.it\/it\/wp-json\/wp\/v2\/categories?post=2950"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/golfclubpetersberg.it\/it\/wp-json\/wp\/v2\/tags?post=2950"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}