{"id":21122,"date":"2023-03-11T11:35:58","date_gmt":"2023-03-11T10:35:58","guid":{"rendered":"https:\/\/golfclubpetersberg.it\/event\/cristal-cup-2023-19\/"},"modified":"2023-06-07T14:34:04","modified_gmt":"2023-06-07T12:34:04","slug":"cristal-cup-2023-19","status":"publish","type":"tribe_events","link":"https:\/\/golfclubpetersberg.it\/it\/event\/cristal-cup-2023-19\/","title":{"rendered":"Cristal Cup 2023"},"content":{"rendered":"<p>WEEKLEY CUP \u2013 HOTEL CRISTAL GOLF CUP<\/p>\n<div class=\"tribe-events-single-event-description tribe-events-content\">\n<p>Jeden Mittwoch findet das vorgabewirksame Stableford-Turnier \u201eCRISTAL CUP\u201c statt.<\/p>\n<p>Die Startzeiten sind zwischen 12.00 Uhr und 14.00 Uhr.<br \/>\nBis 12.00 Uhr und ab 14.00 Uhr kann frei gespielt werden.<br \/>\nDie Anmeldung sollte m\u00f6glichst innerhalb Dienstag Abend gemacht werden.<br \/>\nAnmeldungen k\u00f6nnen aber auch noch am Mittwoch Vormittag gemacht werden, es k\u00f6nnen dann aber nicht mehr alle W\u00fcnsche bez\u00fcglich Startzeit und\/oder Flight-Partner ber\u00fccksichtigt werden.<br \/>\nTurniereinschreibung: \u20ac 15,- f\u00fcr Mitglieder,\u00a0 \u20ac 65 f\u00fcr Mitglieder S\u00fcdtiroler Golfclubs (inklusive Green-Fee) und \u20ac 75,- f\u00fcr G\u00e4ste, inklusive Green-Fee<\/p>\n<p>&nbsp;<\/p>\n<p>Ogni mercoled\u00ec giochiamo la gara stableford\u00a0 \u201eCRISTAL CUP\u201c.<\/p>\n<p>Le partenze sono tra le ore 12.00 e le ore 14.00.<br \/>\nFino alle ore 12.00 e dopo le ore 14.00 si pu\u00f2 giocare liberamente.<br \/>\nLe iscrizioni dovrebbero essere fatte possibilmente entro marted\u00ec sera.<br \/>\n\u00c8 possibile iscriversi anche mercoled\u00ec mattina, non potranno per\u00f2 essere soddisfatte tutte le preferenze di orari e\/o compagni di gioco.<br \/>\nIscrizione gare: 15 \u20ac per i nostri soci, 65 \u20ac per i soci dei circoli dell&#8217;Alto Adige (compreso green-fee) e 75 \u20ac per ospiti, compreso green-fee.<\/p>\n<h3><a href=\"https:\/\/www.hotelcristal.com\/\" target=\"_blank\" rel=\"noopener\">WWW.HOTELCRISTAL.COM<\/a><\/h3>\n<\/div>\n<div class=\"tribe-events-single-event-description tribe-events-content\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>WEEKLEY CUP \u2013 HOTEL CRISTAL GOLF CUP Jeden Mittwoch findet das vorgabewirksame Stableford-Turnier \u201eCRISTAL CUP\u201c&#8230;<\/p>\n","protected":false},"author":4,"featured_media":20993,"template":"","meta":{"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"tags":[],"tribe_events_cat":[],"class_list":["post-21122","tribe_events","type-tribe_events","status-publish","has-post-thumbnail"],"_links":{"self":[{"href":"https:\/\/golfclubpetersberg.it\/it\/wp-json\/wp\/v2\/tribe_events\/21122","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/golfclubpetersberg.it\/it\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/golfclubpetersberg.it\/it\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/golfclubpetersberg.it\/it\/wp-json\/wp\/v2\/users\/4"}],"version-history":[{"count":0,"href":"https:\/\/golfclubpetersberg.it\/it\/wp-json\/wp\/v2\/tribe_events\/21122\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/golfclubpetersberg.it\/it\/wp-json\/wp\/v2\/media\/20993"}],"wp:attachment":[{"href":"https:\/\/golfclubpetersberg.it\/it\/wp-json\/wp\/v2\/media?parent=21122"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/golfclubpetersberg.it\/it\/wp-json\/wp\/v2\/tags?post=21122"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/golfclubpetersberg.it\/it\/wp-json\/wp\/v2\/tribe_events_cat?post=21122"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}