{"id":23797,"date":"2024-02-01T15:50:25","date_gmt":"2024-02-01T14:50:25","guid":{"rendered":"https:\/\/golfclubpetersberg.it\/event\/cristal-cup-2024-20\/"},"modified":"2024-02-01T16:01:36","modified_gmt":"2024-02-01T15:01:36","slug":"cristal-cup-2024-20","status":"publish","type":"tribe_events","link":"https:\/\/golfclubpetersberg.it\/it\/event\/cristal-cup-2024-20\/","title":{"rendered":"CRISTAL CUP 2024"},"content":{"rendered":"<p>WEEKLEY CUP \u2013 HOTEL CRISTAL GOLF CUP<\/p>\n<p><strong>Ogni mercoled\u00ec<\/strong>\u00a0giochiamo la gara stableford\u00a0 \u201eCRISTAL CUP\u201c.<\/p>\n<p>Le partenze sono tra le ore 12.00 e le ore 14.00.<br \/>\nFino alle ore 12.00 e dopo le ore 14.00 si pu\u00f2 giocare liberamente.<br \/>\nLe iscrizioni dovrebbero essere fatte possibilmente entro marted\u00ec sera.<br \/>\n\u00c8 possibile iscriversi anche mercoled\u00ec mattina, non potranno per\u00f2 essere soddisfatte tutte le preferenze di orari e\/o compagni di gioco.<br \/>\nIscrizione gare: 15 \u20ac per i nostri soci, 69 \u20ac per i soci dei circoli dell\u2019Alto Adige (compreso green-fee) e 79 \u20ac per ospiti, compreso green-fee.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Jeden Mittwoch<\/strong>\u00a0findet das vorgabewirksame Stableford-Turnier \u201eCRISTAL CUP\u201c statt.<\/p>\n<p>Die Startzeiten sind zwischen 12.00 Uhr und 14.00 Uhr.<br \/>\nBis 12.00 Uhr und ab 14.00 Uhr kann frei gespielt werden.<br \/>\nDie Anmeldung sollte m\u00f6glichst innerhalb Dienstag Abend gemacht werden.<br \/>\nAnmeldungen k\u00f6nnen aber auch noch am Mittwoch Vormittag gemacht werden, es k\u00f6nnen dann aber nicht mehr alle W\u00fcnsche bez\u00fcglich Startzeit und\/oder Flight-Partner ber\u00fccksichtigt werden.<br \/>\nTurniereinschreibung: 15 \u20ac f\u00fcr Mitglieder, 69 \u20ac f\u00fcr Mitglieder S\u00fcdtiroler Golfclubs (inklusive Green-Fee) und 79 \u20ac f\u00fcr G\u00e4ste, inklusive Green-Fee<\/p>\n<p>&nbsp;<\/p>\n<div class=\"tribe-events-single-event-description tribe-events-content\">\n<h3><a href=\"https:\/\/www.hotelcristal.com\/\" target=\"_blank\" rel=\"noopener\">WWW.HOTELCRISTAL.COM<\/a><\/h3>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>WEEKLEY CUP \u2013 HOTEL CRISTAL GOLF CUP Ogni mercoled\u00ec\u00a0giochiamo la gara stableford\u00a0 \u201eCRISTAL CUP\u201c. Le&#8230;<\/p>\n","protected":false},"author":4,"featured_media":23679,"template":"","meta":{"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"tags":[],"tribe_events_cat":[],"class_list":["post-23797","tribe_events","type-tribe_events","status-publish","has-post-thumbnail"],"_links":{"self":[{"href":"https:\/\/golfclubpetersberg.it\/it\/wp-json\/wp\/v2\/tribe_events\/23797","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/golfclubpetersberg.it\/it\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/golfclubpetersberg.it\/it\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/golfclubpetersberg.it\/it\/wp-json\/wp\/v2\/users\/4"}],"version-history":[{"count":0,"href":"https:\/\/golfclubpetersberg.it\/it\/wp-json\/wp\/v2\/tribe_events\/23797\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/golfclubpetersberg.it\/it\/wp-json\/wp\/v2\/media\/23679"}],"wp:attachment":[{"href":"https:\/\/golfclubpetersberg.it\/it\/wp-json\/wp\/v2\/media?parent=23797"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/golfclubpetersberg.it\/it\/wp-json\/wp\/v2\/tags?post=23797"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/golfclubpetersberg.it\/it\/wp-json\/wp\/v2\/tribe_events_cat?post=23797"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}